{"id":6027,"count":2,"description":"","link":"https:\/\/tripilare.com\/us\/tag\/tenerife-south\/","name":"tenerife south","slug":"tenerife-south","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/tripilare.com\/us\/wp-json\/wp\/v2\/tags\/6027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tripilare.com\/us\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tripilare.com\/us\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tripilare.com\/us\/wp-json\/wp\/v2\/posts?tags=6027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}